{"id":34353,"guid":{"rendered":"https:\/\/graf.cat\/?post_type=event&#038;p=34353"},"modified":"2023-12-18T14:04:30","modified_gmt":"2023-12-18T12:04:30","slug":"taller-16mm-revisant-el-territori-estetiques-obsolescents-com-a-formes-de-resistencia","status":"publish","type":"event","link":"https:\/\/graf.cat\/en\/events\/event\/taller-16mm-revisant-el-territori-estetiques-obsolescents-com-a-formes-de-resistencia\/","title":{"rendered":"Taller 16mm Revisant el Territori \u203a\u203a Est\u00e8tiques Obsolescents com a Formes de Resist\u00e8ncia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":30,"featured_media":34355,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"event-venues":[127],"event-tags":[],"class_list":["post-34353","event","type-event","status-publish","has-post-thumbnail","hentry","event-venue-hangar","event-category-taller"],"acf":{"title_ca":"Taller 16mm Revisant el Territori \u203a\u203a Est\u00e8tiques Obsolescents com a Formes de Resist\u00e8ncia","title_es":"Taller 16 mm Revisando el Territorio \u203a\u203a Est\u00e9ticas Obsolescentes como Formas de Resistencia","title_en":"Taller 16 mm Revisando el Territorio \u203a\u203a Est\u00e9ticas Obsolescentes como Formas de Resistencia","desc_ca":"<b><strong>Un taller de cinema experimental en 16mm amb <a href=\"https:\/\/hamacaonline.net\/authors\/yago\/\">Yago Alcover<\/a> de <a href=\"https:\/\/crater-lab.org\/home\/\">Crater-Lab<\/a>\r\n30, 31 de gener i 1 de febrer a Hangar\r\n<\/strong><\/b>\r\n<div class=\"newspaper col-sm-9\">\r\n\r\nLes possibilitats creatives dels dispositius f\u00edlmics fotoqu\u00edmics estan lluny de la seva pretesa obsolesc\u00e8ncia. No sols aix\u00f2, sin\u00f3 que, a m\u00e9s, des de la seva dimensi\u00f3 mat\u00e8rica i els seus vincles, ens poden servir per a proposar altres mirades i altres experi\u00e8ncies allunyades del nostre contacte permanent amb les imatges en moviment. Lluny del que pogu\u00e9s semblar sovint en la contemporane\u00eftat, els formats anal\u00f2gics no tenen una finalitat merament est\u00e8tica, sin\u00f3 que els dispositius cinematogr\u00e0fics i fotoqu\u00edmics ens serveixen i proporcionen unes limitacions que habiliten unes possibilitats espec\u00edfiques i \u00faniques al\/la cineasta en l'acte de filmar\/crear.\r\n\r\nEn el taller s'exploraran les m\u00faltiples possibilitats durant la filmaci\u00f3 en 16mm: des del camp visual i seq\u00fcencial, fins a les diferents possibilitats d'escriptura estructural i els diversos par\u00e0metres i rangs espacials i temporals que la cambra Bolex ofereix per a afrontar tant el planificat com l'inesperat, que sovint juga un paper determinant en treballar amb t\u00e8cniques anal\u00f2giques per la seva irreversibilitat. Despr\u00e9s de la filmaci\u00f3, es treballaran les enormes possibilitats que ofereix el revelat artesanal i experimental, obrint-se un m\u00f3n est\u00e8tic en el qual les possibilitats de (d-)efectes i\/o errors (controlats o no) ens sorprenguin amb les seves imatges imprevistes.\r\n\r\nAquest taller tracta de reflexionar de manera teoricopr\u00e0ctica sobre les transformacions en el territori immediat que envolta al laboratori i el centre d'arts Hangar, que representen la manera en qu\u00e8 es manifesten algunes de les maneres de poder i transformaci\u00f3 m\u00e9s violentes que sofrim de manera m\u00e9s immediata i plausible: les modificacions urban\u00edstiques. Abordarem el cinema anal\u00f2gic com un aparell que mant\u00e9 multitud de potencialitats des de variades perspectives, tant com element creatiu, com a eina pol\u00edtica i com a dispositiu resistent. Veient els processos d'escriptura, filmaci\u00f3, revelat i finalment la projecci\u00f3, volem descobrir la manera en qu\u00e8 es manifesten els conceptes de control i atzar que ens autoimposem durant els processos de creaci\u00f3 en treballar amb cinema anal\u00f2gic i com, despr\u00e9s, tot aix\u00f2 resulta en una experi\u00e8ncia d'espectadori fora del comuna.\r\n\r\nL'objectiu o resultat final del taller ser\u00e0 la creaci\u00f3 d'una pel\u00b7l\u00edcula col\u00b7lectiva, a partir d'exercicis d'observaci\u00f3 i expressi\u00f3 dividits en diferents grups de treball que se centraran en diferents formes d'aproximaci\u00f3 al conflicte que comporten les transformacions urban\u00edstiques i com podem enfrontar-les amb una de les nostres millors armes: la representaci\u00f3 amb imatges en moviment.\r\n\r\n<u>Sessi\u00f3 1: Teoria i visionat<\/u>\r\nEl dispositiu cinematogr\u00e0fic.\r\nLa imatge fotoqu\u00edmica.\r\nAproximacions a l'espai i el territori al cinema experimental.\r\nObres de Refer\u00e8ncia.\r\n\r\n<u>Sessi\u00f3 2. Filmaci\u00f3<\/u>\r\nLa c\u00e0mera i l'escriptura d'imatges.\r\nFormes d'escriptura visuals i seq\u00fcencials.\r\nEstructures, previsions, improvisacions.\r\n\r\n<u>Sessi\u00f3 3. Revelat<\/u>\r\nEl Laboratori Fotoqu\u00edmic\r\nReceptes per a l'experimentaci\u00f3.\r\nPreparar la projecci\u00f3.\r\n\r\n<strong>A qui va dirigit: <\/strong>\r\nDirigit a artistes, cineastes, estudiants i qualsevol persona interessada en la creaci\u00f3 d'imatges en moviment, la materialitat f\u00edlmica i els processos artesanals de creaci\u00f3 i experimentaci\u00f3 cinematogr\u00e0fica.\r\n\r\n<strong>Qu\u00e8 fa falta portar de casa: <\/strong>\r\nCrater-Lab subministrar\u00e0 tots els materials i dispositius necessaris per a la filmaci\u00f3, el revelat, l'edici\u00f3 i la projecci\u00f3.\r\n\r\n<strong>Durada:<\/strong> 12 hores\r\n<strong>Dates i horari:<\/strong> 30 de gener de 18:00h a 21:00h, 31 de gener de 17:00h a 20:00h, 1 de febrer de 18:00h a 21:00h.\r\n<strong>Preu:<\/strong> 50\u20ac p\u00fablic general \/ 25\u20ac <a href=\"https:\/\/hamacaonline.net\/info\/friends\/\">Amigues Hamaca opci\u00f3 2<\/a>\r\n<strong>Lloc:<\/strong> Hangar (tallers Antigues oficines). C\/ Emilia Coranty 8-16, Barcelona.\r\n\r\n<a href=\"https:\/\/forms.gle\/Ffabubcr5bqkvxdp9\"><strong>\u2192 INSCRIPCIONS <\/strong><\/a>\r\n<a href=\"http:\/\/hamacaonline.net\/authors\/yago\/\"><strong>Yago Alcover Pujol<\/strong><\/a> \u00e9s un cineasta, docent, investigador i m\u00fasic nascut a Barcelona en 1984. Actualment es troba desenvolupant la seva tesi doctoral a la Universitat Pompeu Fabra centrada en el desenvolupament de recerques a trav\u00e9s de pr\u00e0ctiques f\u00edlmiques anal\u00f2giques en la contemporane\u00eftat. \u00c9s membre de la Junta Directiva del Crater-Lab des de l'any 2019. Com a cineasta, les seves pr\u00e0ctiques es mouen des de les pr\u00e0ctiques experimentals sobre l'arxiu, la recerca amb emulsions artesanals, les pr\u00e0ctiques experimentals en formats de cinema sense c\u00e0mera i m\u00e9s recentment el cinema expandit. Ha realitzat diversos curtmetratges i peces audiovisuals en col\u00b7laboraci\u00f3 amb altres artistes de diferents camps. Alguns dels seus treballs es troben en distribuci\u00f3 dins del cat\u00e0leg d'Hamaca.\r\n\r\n<a href=\"http:\/\/crater-lab.org\/home\/\"><strong>Crater-Lab<\/strong><\/a> \u00e9s un laboratori de creaci\u00f3 \/ producci\u00f3 \/ experimentaci\u00f3 i projecci\u00f3 cinematogr\u00e0fica independent, autogestionat per artistes i cineastes. El seu objectiu \u00e9s impulsar la producci\u00f3 d'un cinema artesanal en suport f\u00edlmic, enfocat a generar les bases materials per a crear i experimentar en tots els seus processos (filmaci\u00f3, revelat, copiat, animaci\u00f3, intervenci\u00f3 pl\u00e0stica, projecci\u00f3, etc). La filosofia de Crater-Lab se centra en poder produir cinema lliurement, ser independents, autosostenibles, fer i ser una comunitat cinematogr\u00e0fica, secundar i fer visible obres de nous i consolidats cineastes, ser una plataforma de projecci\u00f3, intercanvi de materials i coneixements, estimular la formaci\u00f3 de noves generacions que puguin vincular-se de manera diferent amb el cinema, crear vincles de col\u00b7laboraci\u00f3 amb altres col\u00b7lectius afins, i fonamentalment generar tots els mitjans per a la creaci\u00f3 en suport f\u00edlmic, com a acte de resist\u00e8ncia, i contribuir de manera activa a la seva continu\u00eftat en un \u00e0mbit creaci\u00f3 lliure i d'experimentaci\u00f3.\r\n\r\nAquest taller pertany al programa <a href=\"https:\/\/hamacaonline.net\/projects\/hamacaapren-amb_artistes2023\/\"><strong><em>#HamacaApr\u00e8n &gt; amb_artistes2023 | 4 cartes d'amor<\/em><\/strong><\/a>.\r\n\r\n<\/div>","desc_es":"<b><strong>Un taller de cine experimental en 16mm con <a href=\"https:\/\/hamacaonline.net\/authors\/yago\/\">Yago Alcover<\/a> de <a href=\"https:\/\/crater-lab.org\/home\/\">Crater-Lab<\/a>\r\n30, 31 de enero y 1 de febrero en Hangar\r\n<\/strong><\/b>\r\n<div class=\"newspaper col-sm-9\">\r\n\r\nLas posibilidades creativas de los dispositivos f\u00edlmicos fotoqu\u00edmicos est\u00e1n lejos de su pretendida obsolescencia. No s\u00f3lo eso, sino que, adem\u00e1s, desde su dimensi\u00f3n mat\u00e9rica y sus v\u00ednculos, nos pueden servir para proponer otras miradas y otras experiencias alejadas de nuestro contacto permanente con las im\u00e1genes en movimiento. Lejos de lo que pudiera parecer a menudo en la contemporaneidad, los formatos anal\u00f3gicos no tienen una finalidad meramente est\u00e9tica, sino que los dispositivos cinematogr\u00e1ficos y fotoqu\u00edmicos nos sirven y proporcionan unas limitaciones que habilitan unas posibilidades espec\u00edficas y \u00fanicas al\/la cineasta en el acto de filmar\/crear.\r\n\r\nEn el taller se explorar\u00e1n las m\u00faltiples posibilidades durante la filmaci\u00f3n en 16mm: desde el campo visual y secuencial, hasta las diferentes posibilidades de escritura estructural y los diversos par\u00e1metros y rangos espaciales y temporales que la c\u00e1mara Bolex ofrece para afrontar tanto lo planificado como lo inesperado, que a menudo juega un papel determinante al trabajar con t\u00e9cnicas anal\u00f3gicas por su irreversibilidad. Tras la filmaci\u00f3n, se trabajar\u00e1n las enormes posibilidades que ofrece el revelado artesanal y experimental, abri\u00e9ndose un mundo est\u00e9tico en el que las posibilidades de (d-)efectos y\/o errores (controlados o no) nos sorprendan con sus im\u00e1genes imprevistas.\r\n\r\nEste taller trata de reflexionar de manera te\u00f3rico-pr\u00e1ctica sobre las transformaciones en el territorio inmediato que rodea al laboratorio y el centro de artes Hangar, que representan el modo en que se manifiestan algunas de las formas de poder y transformaci\u00f3n m\u00e1s violentas que sufrimos de modo m\u00e1s inmediato y plausible: las modificaciones urban\u00edsticas. Abordaremos el cine anal\u00f3gico como un aparato que mantiene multitud de potencialidades desde variadas perspectivas, tanto como elemento creativo, como herramienta pol\u00edtica y como dispositivo resistente. Viendo los procesos de escritura, filmaci\u00f3n, revelado y finalmente la proyecci\u00f3n, queremos descubrir el modo en que se manifiestan los conceptos de control y azar que nos autoimponemos durante los procesos de creaci\u00f3n al trabajar con cine anal\u00f3gico y c\u00f3mo, despu\u00e9s, todo ello resulta en una experiencia espectatorial fuera de lo com\u00fan.\r\n\r\nEl objetivo o resultado final del taller ser\u00e1 la creaci\u00f3n de una pel\u00edcula colectiva, a partir de ejercicios de observaci\u00f3n y expresi\u00f3n divididos en distintos grupos de trabajo que se centrar\u00e1n en diferentes formas de aproximaci\u00f3n al conflicto que entra\u00f1an las transformaciones urban\u00edsticas y c\u00f3mo podemos enfrentarlas con una de nuestras mejores armas: la representaci\u00f3n con im\u00e1genes en movimiento.\r\n\r\n<u>Sesi\u00f3n 1: Teor\u00eda y visionado<\/u>\r\nEl dispositivo cinematogr\u00e1fico.\r\nLa imagen fotoqu\u00edmica.\r\nAproximaciones al espacio y el territorio en el cine experimental.\r\nObras de Referencia.\r\n\r\n<u>Sesi\u00f3n 2. Filmaci\u00f3n<\/u>\r\nLa c\u00e1mara y la escritura de im\u00e1genes.\r\nFormas de escritura visuales y secuenciales.\r\nEstructuras, previsiones, improvisaciones.\r\n\r\n<u>Sesi\u00f3n 3. Revelado<\/u>\r\nEl Laboratorio Fotoqu\u00edmico.\r\nRecetas para la experimentaci\u00f3n.\r\nPreparar la proyecci\u00f3n.\r\n\r\n<strong>A qui\u00e9n va dirigido:<\/strong>\r\nDirigido a artistas, cineastas, estudiantes y cualquier persona interesada en la creaci\u00f3n de im\u00e1genes en movimiento, la materialidad f\u00edlmica y los procesos artesanales de creaci\u00f3n y experimentaci\u00f3n cinematogr\u00e1fica.\r\n\r\n<strong>Qu\u00e9 hace falta traer de casa:<\/strong>\r\nCrater-Lab suministrar\u00e1 todos los materiales y dispositivos necesarios para la filmaci\u00f3n, el revelado, la edici\u00f3n y la proyecci\u00f3n.\r\n\r\n<strong>Duraci\u00f3n:<\/strong> 12 horas\r\n<strong>Fechas y horario:<\/strong> 30 de enero de 18:00h a 21:00h, 31 de enero de 17:00h a 20:00h, 1 de febrero de 18:00h a 21:00h.\r\n<strong>Precio:<\/strong> 50\u20ac p\u00fablico general \/ 25\u20ac Amigas Hamaca opci\u00f3n 2\r\n<strong>Lugar:<\/strong> Hangar (talleres Antiguas oficinas). C\/ Emilia Coranty 8-16, Barcelona.\r\n\r\n<a href=\"https:\/\/forms.gle\/Ffabubcr5bqkvxdp9\"><strong>\u2192 INSCRIPCIONES <\/strong><\/a>\r\n<a href=\"http:\/\/hamacaonline.net\/authors\/yago\/\"><strong>Yago Alcover Pujol<\/strong><\/a> es un cineasta, docente, investigador y m\u00fasico nacido en Barcelona en 1984. Actualmente se encuentra desarrollando su tesis doctoral en la Universitat Pompeu Fabra centrada en el desarrollo de investigaciones a trav\u00e9s de pr\u00e1cticas f\u00edlmicas anal\u00f3gicas en la contemporaneidad. Es miembro de la Junta Directiva del Crater-Lab desde el a\u00f1o 2019. Como cineasta, sus pr\u00e1cticas se mueven desde las pr\u00e1cticas experimentales sobre el archivo, la investigaci\u00f3n con emulsiones artesanales, las pr\u00e1cticas experimentales en formatos de cine sin c\u00e1mara y m\u00e1s recientemente el cine expandido. Ha realizado diversos cortometrajes y piezas audiovisuales en colaboraci\u00f3n con otras artistas de diferentes campos. Algunos de sus trabajos se encuentran en distribuci\u00f3n dentro del cat\u00e1logo de Hamaca.\r\n\r\n<a href=\"http:\/\/crater-lab.org\/home\/\"><strong>Crater-Lab<\/strong><\/a> es un laboratorio de creaci\u00f3n \/ producci\u00f3n \/ experimentaci\u00f3n y proyecci\u00f3n cinematogr\u00e1fica independiente, autogestionado por artistas y cineastas. Su objetivo es impulsar la producci\u00f3n de un cine artesanal en soporte f\u00edlmico, enfocado en generar las bases materiales para crear y experimentar en todos sus procesos (filmaci\u00f3n, revelado, copiado, animaci\u00f3n, intervenci\u00f3n pl\u00e1stica, proyecci\u00f3n, etc). La filosof\u00eda de Crater-Lab se centra en poder producir cine libremente, ser independientes, autosostenibles, hacer y ser una comunidad cinematogr\u00e1fica, apoyar y hacer visible obras de nuevos y consolidados cineastas, ser una plataforma de proyecci\u00f3n, intercambio de materiales y conocimientos, estimular la formaci\u00f3n de nuevas generaciones que puedan vincularse de forma distinta con el cine, crear v\u00ednculos de colaboraci\u00f3n con otros colectivos afines, y fundamentalmente generar todos los medios para la creaci\u00f3n en soporte f\u00edlmico, como acto de resistencia, y contribuir de forma activa a su continuidad en un \u00e1mbito creaci\u00f3n libre y de experimentaci\u00f3n.\r\n\r\nEste taller pertenece al programa <a href=\"https:\/\/hamacaonline.net\/projects\/hamacaapren-amb_artistes2023\/\"><strong><em>#HamacaAprende &gt; con_artistas2023 | 4 cartas de amor<\/em><\/strong><\/a>.\r\n\r\n<\/div>","desc_en":"","event_category":235,"event_show_only_own_date":true,"_event_confirmed":true,"_event_public":true,"_event_free":false,"_event_price-min":25,"_event_price-max":50,"_event_web_ca":"https:\/\/hamacaonline.net\/projects\/revisant-el-territori\/","_event_web_es":"https:\/\/hamacaonline.net\/projects\/revisant-el-territori\/","_event_web_en":"https:\/\/hamacaonline.net\/projects\/revisant-el-territori\/","event_contact_email":"info@hamacaonline.net","event_apply_email":"https:\/\/hamacaonline.net\/projects\/revisant-el-territori\/","is_online_event":false,"is_art_nou_event":false,"is_bgw_event":false,"date_text":"30 de enero de 18:00h a 21:00h, 31 de enero de 17:00h a 20:00h, 1 de febrero de 18:00h a 21:00h","register_deadline":null,"altres_organitzadors":null},"abe_event_venue":"Hangar","abe_event_category":"Taller","start":"2024-01-30 18:00:00","end":"2024-02-01 21:00:00","schedule":"once","schedule_meta":"","frequency":1,"all_day":0,"until":"2024-01-30 18:00:00","include":[],"exclude":[],"_links":{"self":[{"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/events\/34353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/users\/30"}],"occurrences":[{"embeddable":true,"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/events\/34353\/occurrences"}],"acf:term":[{"embeddable":true,"taxonomy":"event-category","href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/event-category\/235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/media\/34355"}],"wp:attachment":[{"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/media?parent=34353"}],"wp:term":[{"taxonomy":"event-venue","embeddable":true,"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/event-venues?post=34353"},{"taxonomy":"event-tag","embeddable":true,"href":"https:\/\/graf.cat\/en\/wp-json\/wp\/v2\/event-tags?post=34353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}